{"id":15170,"date":"2024-02-20T14:33:02","date_gmt":"2024-02-20T20:33:02","guid":{"rendered":"https:\/\/maiglobal.org\/?page_id=15170"},"modified":"2024-07-02T17:25:44","modified_gmt":"2024-07-02T22:25:44","slug":"concurso-literario-littworld-2024-spanish","status":"publish","type":"page","link":"https:\/\/maiglobal.org\/zh\/concurso-literario-littworld-2024-spanish\/","title":{"rendered":"\u6587\u5b66\u7ade\u8d5b LittWorld 2024\uff08\u897f\u73ed\u7259\u8bed\uff09"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"15170\" class=\"elementor elementor-15170\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4e58150 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4e58150\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-254c9fd\" data-id=\"254c9fd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-43aa176 elementor-widget elementor-widget-image\" data-id=\"43aa176\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"315\" src=\"https:\/\/maiglobal.org\/wp-content\/uploads\/2024\/02\/LittWorld-website-headings-1.png\" class=\"attachment-full size-full wp-image-15171\" alt=\"Concurso Literario LittWorld 2024\" srcset=\"https:\/\/maiglobal.org\/wp-content\/uploads\/2024\/02\/LittWorld-website-headings-1.png 1200w, https:\/\/maiglobal.org\/wp-content\/uploads\/2024\/02\/LittWorld-website-headings-1-300x79.png 300w, https:\/\/maiglobal.org\/wp-content\/uploads\/2024\/02\/LittWorld-website-headings-1-600x158.png 600w, https:\/\/maiglobal.org\/wp-content\/uploads\/2024\/02\/LittWorld-website-headings-1-1024x269.png 1024w, https:\/\/maiglobal.org\/wp-content\/uploads\/2024\/02\/LittWorld-website-headings-1-768x202.png 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9ae9b1c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9ae9b1c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c07ba89\" data-id=\"c07ba89\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e3c90f8 elementor-widget elementor-widget-image\" data-id=\"e3c90f8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/maiglobal.org\/wp-content\/uploads\/2024\/07\/LW-Spanish-WC-1.png\" class=\"attachment-full size-full wp-image-16100\" alt=\"\" srcset=\"https:\/\/maiglobal.org\/wp-content\/uploads\/2024\/07\/LW-Spanish-WC-1.png 600w, https:\/\/maiglobal.org\/wp-content\/uploads\/2024\/07\/LW-Spanish-WC-1-300x300.png 300w, https:\/\/maiglobal.org\/wp-content\/uploads\/2024\/07\/LW-Spanish-WC-1-100x100.png 100w, https:\/\/maiglobal.org\/wp-content\/uploads\/2024\/07\/LW-Spanish-WC-1-150x150.png 150w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-7ffd586\" data-id=\"7ffd586\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48ffb3a elementor-widget elementor-widget-text-editor\" data-id=\"48ffb3a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-size: 16px; font-style: normal; font-weight: 400;\">Media Associates International se complace en anunciar los ganadores del Concurso Literario de LittWorld 2024 de la siguiente manera:<\/p><ul style=\"font-size: 16px; font-style: normal; font-weight: 400;\"><li style=\"font-size: 16px;\">Primer lugar (ingl\u00e9s):\u00a0<a href=\"https:\/\/maiglobal.org\/zh\/meeting-with-a-book-by-daniel-nalbantski\/\" target=\"_blank\" rel=\"noopener\"><em>Meeting with a book<\/em><\/a>\u00a0(&#8220;Encuentro con un libro&#8221;)\u00a0por Daniel Nalbantski<\/li><li style=\"font-size: 16px;\">Primer lugar (espa\u00f1ol):\u00a0<a href=\"https:\/\/maiglobal.org\/zh\/amor-en-letras-por-karen-suarez\/\" target=\"_blank\" rel=\"noopener\"><em>Amor en letras<\/em><\/a>\u00a0por\u00a0Karen Su\u00e1rez<\/li><li style=\"font-size: 16px;\">Segundo lugar (ingl\u00e9s):\u00a0<a href=\"https:\/\/maiglobal.org\/zh\/what-are-you-doing-here-by-dawn-moran-castro\/\" target=\"_blank\" rel=\"noopener\"><em>What are you doing here<\/em>?<\/a>\u00a0(&#8220;\u00bfQu\u00e9 haces aqu\u00ed?&#8221;) por\u00a0Dawn Moran Castro<\/li><li style=\"font-size: 16px;\">Segundo lugar (espa\u00f1ol):\u00a0<a href=\"https:\/\/maiglobal.org\/zh\/mas-de-lo-que-pedimos-o-entendemos-por-dr-jorge-batch\/\" target=\"_blank\" rel=\"noopener\"><em>M\u00e1s de lo que pedimos o entendemos<\/em><\/a>\u00a0por Dr. Jorge Batch<\/li><\/ul><p>Los participantes del concurso fueron invitados a escribir bajo la consigna: \u201cDescribe una de tus experiencias m\u00e1s memorables y sobresalientes al escribir o publicar en el mundo cristiano. \u00bfQu\u00e9 aprendiste de esta experiencia? Concluye con un consejo para alguien que est\u00e1 decidiendo si ser parte o no del ministerio de publicaciones cristianas\u201d.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-354ed8d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"354ed8d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c1b11ea\" data-id=\"c1b11ea\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8c2978f elementor-widget elementor-widget-image\" data-id=\"8c2978f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/maiglobal.org\/wp-content\/uploads\/2024\/07\/Spanish-winners-2.png\" class=\"attachment-full size-full wp-image-16101\" alt=\"\" srcset=\"https:\/\/maiglobal.org\/wp-content\/uploads\/2024\/07\/Spanish-winners-2.png 600w, https:\/\/maiglobal.org\/wp-content\/uploads\/2024\/07\/Spanish-winners-2-300x300.png 300w, https:\/\/maiglobal.org\/wp-content\/uploads\/2024\/07\/Spanish-winners-2-100x100.png 100w, https:\/\/maiglobal.org\/wp-content\/uploads\/2024\/07\/Spanish-winners-2-150x150.png 150w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-a1ce45d\" data-id=\"a1ce45d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-07269e5 elementor-widget elementor-widget-text-editor\" data-id=\"07269e5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3 dir=\"ltr\" style=\"font-size: 1.66667rem; font-style: normal;\" aria-label=\"Translated text\" data-placeholder=\"Translation\" data-ved=\"2ahUKEwiPi-CRjfqGAxVEslYBHUTwDqEQ3ewLegQIBRAU\"><span style=\"font-weight: bold;\">Ganadores en espa\u00f1ol del Concurso Literario LittWorld 2024<\/span><\/h3>\n<p style=\"font-size: 16px; font-style: normal; font-weight: 400; color: #7a7a7a;\">Nos complace anunciar que Karen Su\u00e1rez es la ganadora en espa\u00f1ol del Concurso Literario de LittWorld 2024 con su escrito&nbsp;<a href=\"https:\/\/maiglobal.org\/zh\/amor-en-letras-por-karen-suarez\/\" target=\"_blank\" rel=\"noopener\"><em>Amor en letras<\/em><\/a>. El art\u00edculo del Dr. Jorge Batch de Argentina,&nbsp;<a href=\"https:\/\/maiglobal.org\/zh\/mas-de-lo-que-pedimos-o-entendemos-por-dr-jorge-batch\/\" target=\"_blank\" rel=\"noopener\"><em>M\u00e1s de lo que pedimos o entendemos<\/em><\/a>, gan\u00f3 el segundo lugar.<\/p>\n<p style=\"font-size: 16px; font-style: normal; font-weight: 400; color: #7a7a7a;\"><span style=\"font-weight: bold;\">Karen Su\u00e1rez<\/span>&nbsp;es costarricense. Se ha dedicado a la ense\u00f1anza del espa\u00f1ol y tambi\u00e9n es profesora de Nuevo Testamento. Es autora del libro&nbsp;<em>Perfume de gozo<\/em>&nbsp;y de los cuentos&nbsp;<em>Aquel viernes<\/em>&nbsp;y&nbsp;<em>Celeste y las piedras preciosas<\/em>.&nbsp;<\/p>\n<p style=\"font-size: 16px; font-style: normal; font-weight: 400; color: #7a7a7a;\"><span style=\"font-weight: bold;\">Jorge Batch&nbsp;<\/span>es pastor, m\u00e9dico cirujano, consejero pastoral y consejero en Enfoque a la Familia (habla hispana). Ha escrito dos libros:&nbsp;<em>H\u00e1bitos saludables para una vida mejor<\/em>&nbsp;y&nbsp;<em>H\u00e1bitos saludables para una familia feliz<\/em>.&nbsp; Est\u00e1 casado, tiene dos hijos y cuatro nietos. Vive en Buenos Aires, Argentina.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ee39570 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ee39570\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-730a841\" data-id=\"730a841\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-538da93 elementor-widget elementor-widget-text-editor\" data-id=\"538da93\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Unos 45 escritores de todo Am\u00e9rica Latina participaron del concurso, que ofrec\u00eda un premio de 300 d\u00f3lares para el primer lugar y 150 d\u00f3lares para el segundo.<\/p><p>Los escritos fueron evaluados por un jurado de tres editores destacados:\u00a0<\/p><p><strong>Diana Gonz\u00e1lez<\/strong>\u00a0se gradu\u00f3 como licenciada en Letras en Bah\u00eda Blanca, Argentina, y tiene un doctorado en Ling\u00fc\u00edstica, graduada en G\u00f6ttingen, Alemania. Ha dado clases de Lengua y Literatura Hisp\u00e1nica en universidades de M\u00e9xico y Estados Unidos, y de Ling\u00fc\u00edstica en Per\u00fa. Durante varios a\u00f1os trabaj\u00f3 como editora para un ministerio de publicaciones en Costa Rica.<\/p><p><strong>Sara Trejo\u00a0<\/strong>de Hern\u00e1ndez es licenciada en Ciencias de la Comunicaci\u00f3n de la UNAM. Desde hace 22 a\u00f1os, trabaja en Milamex (Misi\u00f3n Latinoamericana de M\u00e9xico), en el \u00e1rea editorial. Con su esposo, Marino Hern\u00e1ndez, dirige el departamento de Educaci\u00f3n de Avanzados en la Iglesia Bautista Horeb, de la Ciudad de M\u00e9xico.<\/p><p><strong>La Dra. Patricia Adrianz\u00e9n de Vergara<\/strong>\u00a0es ministra oficial de la Iglesia Alianza Cristiana y Misionera del Per\u00fa, donde ejerce el ministerio desde hace 35 a\u00f1os junto a su esposo, el Rvdo. Roger Vergara. Es bachiller en Literatura de la Facultad de Letras y Ciencias Humanas de\u00a0la Universidad Nacional Mayor de San Marcos, m\u00e1ster en Teolog\u00eda (Universidad Evang\u00e9lica de las Am\u00e9ricas, Costa Rica) y doctora en Teolog\u00eda. Dirige Ediciones Verbo Vivo, es autora de m\u00e1s de veinte libros y editora de otros autores latinoamericanos.<\/p><p>Acerca del art\u00edculo ganador,\u00a0<em>Amor en letras<\/em>, la Sra. Adrianz\u00e9n dijo: \u201cEs cautivante y motivador.\u00a0 Transmite el aprendizaje de vida de una escritora novata con un estilo literario sencillo y tierno\u201d.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-20e451f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"20e451f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-80c89d6\" data-id=\"80c89d6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-248fa70 elementor-widget elementor-widget-image\" data-id=\"248fa70\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/maiglobal.org\/wp-content\/uploads\/2024\/07\/English-winners-2-1.png\" class=\"attachment-full size-full wp-image-16102\" alt=\"\" srcset=\"https:\/\/maiglobal.org\/wp-content\/uploads\/2024\/07\/English-winners-2-1.png 600w, https:\/\/maiglobal.org\/wp-content\/uploads\/2024\/07\/English-winners-2-1-300x300.png 300w, https:\/\/maiglobal.org\/wp-content\/uploads\/2024\/07\/English-winners-2-1-100x100.png 100w, https:\/\/maiglobal.org\/wp-content\/uploads\/2024\/07\/English-winners-2-1-150x150.png 150w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-930dc06\" data-id=\"930dc06\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-74fff78 elementor-widget elementor-widget-text-editor\" data-id=\"74fff78\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3 dir=\"ltr\" style=\"font-size: 1.66667rem; font-style: normal;\" aria-label=\"Translated text\" data-placeholder=\"Translation\" data-ved=\"2ahUKEwiPi-CRjfqGAxVEslYBHUTwDqEQ3ewLegQIBRAU\"><span style=\"font-weight: bold;\">Ganadores en ingl\u00e9s\u00a0del Concurso Literario\u00a0LittWorld 2024<\/span><\/h3><p style=\"font-size: 16px; font-style: normal; font-weight: 400; color: #7a7a7a;\">Por su art\u00edculo\u00a0<a href=\"https:\/\/maiglobal.org\/zh\/meeting-with-a-book-by-daniel-nalbantski\/\" target=\"_blank\" rel=\"noopener\"><em>Meeting with a book<\/em><\/a>\u00a0(&#8220;Encuentro con un libro&#8221;), el escritor y pastor b\u00falgaro\u00a0<span style=\"font-weight: bold;\">Daniel Nalbantski\u00a0<\/span>fue seleccionado como ganador del primer lugar en el concurso de escritura LittWorld 2024.\u00a0<span style=\"font-weight: bold;\">Dawn Moran Castro<\/span>\u00a0de Filipinas termin\u00f3 en segundo lugar con su art\u00edculo\u00a0<a href=\"https:\/\/maiglobal.org\/zh\/what-are-you-doing-here-by-dawn-moran-castro\/\" target=\"_blank\" rel=\"noopener\"><em>What are you doing here<\/em>?<\/a>\u00a0(&#8220;\u00bfQu\u00e9 haces aqu\u00ed?&#8221;).<\/p><p style=\"font-size: 16px; font-style: normal; font-weight: 400; color: #7a7a7a;\">Casi 75 escritores de todo el mundo presentaron trabajos al concurso.\u00a0 Un distinguido panel de jueces evalu\u00f3 las presentaciones seg\u00fan su contenido, creatividad, calidad de escritura e impacto general.\u00a0 Los premios para el primer y segundo lugar fueron $300 y $150, respectivamente.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-246614d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"246614d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a65364f\" data-id=\"a65364f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b46137 elementor-widget elementor-widget-text-editor\" data-id=\"3b46137\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Al comentar sobre el art\u00edculo premiado de Daniel, la jueza del concurso Marlene Legaspi-Munar elogi\u00f3 su \u201cnarrativa trepidante llena de detalles claros y relevantes.\u00a0 Los acontecimientos de esta historia parecen el argumento de una pel\u00edcula con varias sorpresas\u201d.<\/p><p>El juez del concurso, Dr. Muthoni Omukhango, se\u00f1al\u00f3: &#8220;Este es un art\u00edculo sincero e inspirador que comunica de manera efectiva la importancia de la escritura y su influencia inesperada en los dem\u00e1s&#8221;.<\/p><p>Respecto al art\u00edculo de Dawn, la jueza del concurso Marlene Legaspi-Munar dijo: \u201cLa memorable experiencia compartida por la escritora es simple pero la reflexi\u00f3n es profunda.\u00a0 La escritora entrelaza eficazmente su experiencia personal y sus luchas emocionales con la experiencia de El\u00edas en el desierto\u201d.<\/p><p>&#8220;Las habilidades narrativas de Daniel explican por qu\u00e9 esta es la tercera vez que \u00e9l gana el concurso de escritura LittWorld desde que se inici\u00f3 en 2002: una haza\u00f1a significativa&#8221;, dijo el presidente del MAI, John Maust.\u00a0 Su art\u00edculo fue traducido del b\u00falgaro al ingl\u00e9s por su hija Biliana Nalbantska.<\/p><p>Daniel comenz\u00f3 su ministerio en la era comunista, cuando ser cristiano era peligroso y convertirse en ministro pod\u00eda generar problemas inimaginables. Form\u00f3 parte de un movimiento clandestino involucrado en la traducci\u00f3n y publicaci\u00f3n de libros cristianos que su esposa escrib\u00eda en una m\u00e1quina de escribir y que distribu\u00edan en secreto entre los creyentes.<\/p><p>Despu\u00e9s de la ca\u00edda del Tel\u00f3n de Acero a principios de la d\u00e9cada de 1990, Daniel comenz\u00f3 a escribir novelas cristianas y una gu\u00eda devocional diaria que todav\u00eda llega a los lectores despu\u00e9s de 20 a\u00f1os. Es autor de 15 novelas y una colecci\u00f3n de cuentos, e incluso escribe poes\u00eda. Daniel vive en Russe, Bulgaria, con su esposa. Le encanta nadar, hacer excursiones y jardiner\u00eda en el peque\u00f1o jard\u00edn de su patio trasero. Es padre de dos hijas y tiene tres nietas.<\/p><p>La ganadora del segundo premio, Dawn Moran Castro, compet\u00eda por primera vez en un concurso de escritura de MAI.\u00a0 Es terapeuta conductual, especialista en comunicaciones, discipuladora, asistente ejecutiva, psicometrista, investigadora y maestra de escuela dominical a lo largo de varias etapas de su vida. Termin\u00f3 su Maestr\u00eda en Relaciones Industriales de la Escuela de Relaciones Laborales e Industriales de la Universidad de Filipinas Diliman. Renunci\u00f3 a la Sociedad B\u00edblica de Filipinas para abrazar por el momento su papel de esposa y madre. Naci\u00f3 en un campo de refugiados en Bataan, creci\u00f3 en Jeddah y vivi\u00f3 mucho tiempo en Manila. Hoy vive en Laguna con su esposo y sus dos hijos. Sue\u00f1a con tener su propia biblioteca familiar y escribir un libro.<\/p><p>MAI expresa su profundo agradecimiento al panel de tres jueces, que invirtieron muchas horas de arduo trabajo leyendo y evaluando las presentaciones del concurso.\u00a0 Ellos son:<\/p><p><strong>Tim Gustafson.\u00a0<\/strong>Es editor en jefe y desarrollador de contenido de\u00a0<em>Our Daily Bread Ministries<\/em>\u00a0en Grand Rapids, Michigan, EE. UU., donde se ha desempe\u00f1ado como editor y escritor durante m\u00e1s de 30 a\u00f1os. Colaborador habitual del devocional Nuestro Pan Diario, es autor del libro devocional\u00a0<em>Hermano a hermano.<\/em>\u00a0\u00c9l y su esposa, Leisa, tienen ocho hijos y dos nietos. Los vers\u00edculos de resaltan su vida son: \u201cPadre de los hu\u00e9rfanos, defensor de las viudas, \u00e9ste es Dios en su santa morada. \u00c9l coloca a los solitarios en familias y conduce a los cautivos a la libertad\u201d (Salmo 68:5-6).<\/p><p><strong>Marlene Legaspi-Munar.\u00a0\u00a0<\/strong>Adem\u00e1s de escribir devocionales, materiales curriculares y libros inspiradores, Marlene tambi\u00e9n traduce y edita desde su casa en Filipinas. Tambi\u00e9n asesora a ni\u00f1os y adolescentes a trav\u00e9s de sus clases de escritura en l\u00ednea. Encu\u00e9ntrala en Facebook y LinkedIn.<\/p><p><strong>Dr. Muthoni Omukhango.\u00a0\u00a0<\/strong>Es una editora distinguida en \u00c1frica, mentor de autores, convocante del Premio del Libro de Autores Cristianos Africanos (ACABA), ministra de mercado y directora nacional de CVX Kenia, dedicada a promover el Reino de Dios a trav\u00e9s de la literatura.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-305c447 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"305c447\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-87981e9\" data-id=\"87981e9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-733ce66 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"733ce66\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/www.eventbee.com\/v\/littworld-2024\/event?eid=214912434#\/tickets\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">REG\u00cdSTRESE PARA LITTWORLD<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2c2480e\" data-id=\"2c2480e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-caf6937 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"caf6937\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/maiglobal.org\/zh\/orar-por-littworld-2024\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">ORAR POR LITTWORLD 2024<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c2d271a\" data-id=\"c2d271a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-81c16b9 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"81c16b9\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/maiglobal.org\/zh\/oradores-de-littworld-2024\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">ORADORES DE LITTWORLD<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-36440c8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"36440c8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d683109\" data-id=\"d683109\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-546cb09 elementor-widget elementor-widget-spacer\" data-id=\"546cb09\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Media Associates International se complace en anunciar los ganadores del Concurso Literario de LittWorld 2024 de la siguiente manera: Primer lugar (ingl\u00e9s):\u00a0Meeting with a book\u00a0(&#8220;Encuentro con un libro&#8221;)\u00a0por Daniel Nalbantski Primer lugar (espa\u00f1ol):\u00a0Amor en letras\u00a0por\u00a0Karen Su\u00e1rez Segundo lugar (ingl\u00e9s):\u00a0What are you doing here?\u00a0(&#8220;\u00bfQu\u00e9 haces aqu\u00ed?&#8221;) por\u00a0Dawn Moran Castro Segundo lugar (espa\u00f1ol):\u00a0M\u00e1s de lo que pedimos [&hellip;]<\/p>","protected":false},"author":7,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"give_campaign_id":0,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"iawp_total_views":707,"footnotes":""},"class_list":["post-15170","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Concurso literario LittWorld 2024 (Spanish) - Media Associates International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maiglobal.org\/zh\/concurso-literario-littworld-2024-spanish\/\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Concurso literario LittWorld 2024 (Spanish) - Media Associates International\" \/>\n<meta property=\"og:description\" content=\"Media Associates International se complace en anunciar los ganadores del Concurso Literario de LittWorld 2024 de la siguiente manera: Primer lugar (ingl\u00e9s):\u00a0Meeting with a book\u00a0(&#8220;Encuentro con un libro&#8221;)\u00a0por Daniel Nalbantski Primer lugar (espa\u00f1ol):\u00a0Amor en letras\u00a0por\u00a0Karen Su\u00e1rez Segundo lugar (ingl\u00e9s):\u00a0What are you doing here?\u00a0(&#8220;\u00bfQu\u00e9 haces aqu\u00ed?&#8221;) por\u00a0Dawn Moran Castro Segundo lugar (espa\u00f1ol):\u00a0M\u00e1s de lo que pedimos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maiglobal.org\/zh\/concurso-literario-littworld-2024-spanish\/\" \/>\n<meta property=\"og:site_name\" content=\"Media Associates International\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-02T22:25:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/maiglobal.org\/wp-content\/uploads\/2024\/02\/LittWorld-website-headings-1.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 \u5206\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/maiglobal.org\/concurso-literario-littworld-2024-spanish\/\",\"url\":\"https:\/\/maiglobal.org\/concurso-literario-littworld-2024-spanish\/\",\"name\":\"Concurso literario LittWorld 2024 (Spanish) - Media Associates International\",\"isPartOf\":{\"@id\":\"https:\/\/maiglobal.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/maiglobal.org\/concurso-literario-littworld-2024-spanish\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/maiglobal.org\/concurso-literario-littworld-2024-spanish\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/maiglobal.org\/wp-content\/uploads\/2024\/02\/LittWorld-website-headings-1.png\",\"datePublished\":\"2024-02-20T20:33:02+00:00\",\"dateModified\":\"2024-07-02T22:25:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/maiglobal.org\/concurso-literario-littworld-2024-spanish\/#breadcrumb\"},\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/maiglobal.org\/concurso-literario-littworld-2024-spanish\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\/\/maiglobal.org\/concurso-literario-littworld-2024-spanish\/#primaryimage\",\"url\":\"https:\/\/maiglobal.org\/wp-content\/uploads\/2024\/02\/LittWorld-website-headings-1.png\",\"contentUrl\":\"https:\/\/maiglobal.org\/wp-content\/uploads\/2024\/02\/LittWorld-website-headings-1.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/maiglobal.org\/concurso-literario-littworld-2024-spanish\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/maiglobal.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Concurso literario LittWorld 2024 (Spanish)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/maiglobal.org\/#website\",\"url\":\"https:\/\/maiglobal.org\/\",\"name\":\"Media Associates International\",\"description\":\"The power of the written word transforms lives.\",\"publisher\":{\"@id\":\"https:\/\/maiglobal.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/maiglobal.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-Hans\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/maiglobal.org\/#organization\",\"name\":\"Media Associates International\",\"url\":\"https:\/\/maiglobal.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\/\/maiglobal.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/maiglobal.org\/wp-content\/uploads\/2017\/01\/maismall.jpg\",\"contentUrl\":\"https:\/\/maiglobal.org\/wp-content\/uploads\/2017\/01\/maismall.jpg\",\"width\":145,\"height\":60,\"caption\":\"Media Associates International\"},\"image\":{\"@id\":\"https:\/\/maiglobal.org\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Concurso literario LittWorld 2024 (Spanish) - Media Associates International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maiglobal.org\/zh\/concurso-literario-littworld-2024-spanish\/","og_locale":"zh_CN","og_type":"article","og_title":"Concurso literario LittWorld 2024 (Spanish) - Media Associates International","og_description":"Media Associates International se complace en anunciar los ganadores del Concurso Literario de LittWorld 2024 de la siguiente manera: Primer lugar (ingl\u00e9s):\u00a0Meeting with a book\u00a0(&#8220;Encuentro con un libro&#8221;)\u00a0por Daniel Nalbantski Primer lugar (espa\u00f1ol):\u00a0Amor en letras\u00a0por\u00a0Karen Su\u00e1rez Segundo lugar (ingl\u00e9s):\u00a0What are you doing here?\u00a0(&#8220;\u00bfQu\u00e9 haces aqu\u00ed?&#8221;) por\u00a0Dawn Moran Castro Segundo lugar (espa\u00f1ol):\u00a0M\u00e1s de lo que pedimos [&hellip;]","og_url":"https:\/\/maiglobal.org\/zh\/concurso-literario-littworld-2024-spanish\/","og_site_name":"Media Associates International","article_modified_time":"2024-07-02T22:25:44+00:00","og_image":[{"url":"https:\/\/maiglobal.org\/wp-content\/uploads\/2024\/02\/LittWorld-website-headings-1.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4":"7 \u5206"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/maiglobal.org\/concurso-literario-littworld-2024-spanish\/","url":"https:\/\/maiglobal.org\/concurso-literario-littworld-2024-spanish\/","name":"Concurso literario LittWorld 2024 (Spanish) - Media Associates International","isPartOf":{"@id":"https:\/\/maiglobal.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/maiglobal.org\/concurso-literario-littworld-2024-spanish\/#primaryimage"},"image":{"@id":"https:\/\/maiglobal.org\/concurso-literario-littworld-2024-spanish\/#primaryimage"},"thumbnailUrl":"https:\/\/maiglobal.org\/wp-content\/uploads\/2024\/02\/LittWorld-website-headings-1.png","datePublished":"2024-02-20T20:33:02+00:00","dateModified":"2024-07-02T22:25:44+00:00","breadcrumb":{"@id":"https:\/\/maiglobal.org\/concurso-literario-littworld-2024-spanish\/#breadcrumb"},"inLanguage":"zh-Hans","potentialAction":[{"@type":"ReadAction","target":["https:\/\/maiglobal.org\/concurso-literario-littworld-2024-spanish\/"]}]},{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/maiglobal.org\/concurso-literario-littworld-2024-spanish\/#primaryimage","url":"https:\/\/maiglobal.org\/wp-content\/uploads\/2024\/02\/LittWorld-website-headings-1.png","contentUrl":"https:\/\/maiglobal.org\/wp-content\/uploads\/2024\/02\/LittWorld-website-headings-1.png"},{"@type":"BreadcrumbList","@id":"https:\/\/maiglobal.org\/concurso-literario-littworld-2024-spanish\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/maiglobal.org\/"},{"@type":"ListItem","position":2,"name":"Concurso literario LittWorld 2024 (Spanish)"}]},{"@type":"WebSite","@id":"https:\/\/maiglobal.org\/#website","url":"https:\/\/maiglobal.org\/","name":"Media Associates International","description":"The power of the written word transforms lives.","publisher":{"@id":"https:\/\/maiglobal.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/maiglobal.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-Hans"},{"@type":"Organization","@id":"https:\/\/maiglobal.org\/#organization","name":"Media Associates International","url":"https:\/\/maiglobal.org\/","logo":{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/maiglobal.org\/#\/schema\/logo\/image\/","url":"https:\/\/maiglobal.org\/wp-content\/uploads\/2017\/01\/maismall.jpg","contentUrl":"https:\/\/maiglobal.org\/wp-content\/uploads\/2017\/01\/maismall.jpg","width":145,"height":60,"caption":"Media Associates International"},"image":{"@id":"https:\/\/maiglobal.org\/#\/schema\/logo\/image\/"}}]}},"campaignId":"","_links":{"self":[{"href":"https:\/\/maiglobal.org\/zh\/wp-json\/wp\/v2\/pages\/15170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maiglobal.org\/zh\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/maiglobal.org\/zh\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/maiglobal.org\/zh\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/maiglobal.org\/zh\/wp-json\/wp\/v2\/comments?post=15170"}],"version-history":[{"count":18,"href":"https:\/\/maiglobal.org\/zh\/wp-json\/wp\/v2\/pages\/15170\/revisions"}],"predecessor-version":[{"id":16105,"href":"https:\/\/maiglobal.org\/zh\/wp-json\/wp\/v2\/pages\/15170\/revisions\/16105"}],"wp:attachment":[{"href":"https:\/\/maiglobal.org\/zh\/wp-json\/wp\/v2\/media?parent=15170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}